{"id":1777,"date":"2024-09-04T17:15:15","date_gmt":"2024-09-04T15:15:15","guid":{"rendered":"https:\/\/allomaman.tk\/?p=143"},"modified":"2024-09-04T17:15:15","modified_gmt":"2024-09-04T15:15:15","slug":"lastigmatisme-une-trouble-de-vue-frequente-chez-lhomme","status":"publish","type":"post","link":"https:\/\/makedamagazine.com\/blog\/lastigmatisme-une-trouble-de-vue-frequente-chez-lhomme\/","title":{"rendered":"L\u2019astigmatisme : une trouble de vue fr\u00e9quente chez l\u2019homme"},"content":{"rendered":"<p>L\u2019astigmatisme fait partie des maladies oculaires rencontr\u00e9s chez l\u2019homme. C\u2019est une maladie tr\u00e8s g\u00eanante car elle perturbe \u00e0 la fois la vision de pr\u00e8s et la vision de loin. Ainsi, lorsque vous ressentez une quelconque fatigue visuelle, il est conseill\u00e9 de vous rendre rapidement chez un ophtalmologue.<!--more--><\/p>\n<h2>C\u2019est quoi l\u2019astigmatisme, \u00eatre astigmate ?<\/h2>\n<p><iframe loading=\"lazy\" title=\"L&#039;astigmatisme expliqu\u00e9\" width=\"735\" height=\"413\" src=\"https:\/\/www.youtube.com\/embed\/el6PBuxDa4g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>Normalement, la corn\u00e9e est de forme ronde. Dans le cas de l\u2019astigmatisme, on observe une forme plut\u00f4t ovale, voire bossel\u00e9e. De ce fait, au lieu de converger vers un seul et m\u00eame point et de fournir ainsi une image nette, les rayons lumineux se \u00ab dispersent \u00bb et produisent une image d\u00e9form\u00e9e. De pr\u00e8s comme de loin, les lignes horizontales et verticales paraissent floues. Certaines lettres sont confondues, comme le H, le M et le N ou le E et le B.<\/p>\n<p>Tr\u00e8s fr\u00e9quent, ce trouble n\u2019affecte pas n\u00e9cessairement la vue. Tout le monde pr\u00e9senterait un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Astigmatisme\">astigmatisme<\/a> qu\u2019il ne serait pas forc\u00e9ment n\u00e9cessaire de corriger. Il peut se manifester d\u00e8s la naissance ou appara\u00eetre plus tard, \u00e0 la suite d\u2019une plaie corn\u00e9enne perforante, d\u2019une infection ou d\u2019un k\u00e9ratoc\u00f4ne (lorsque la corn\u00e9e prend la forme d\u2019un c\u00f4ne). Si le cristallin pr\u00e9sente lui aussi une d\u00e9formation, on parle d\u2019astigmatisme total. Seul l\u2019astigmatisme d\u2019origine cong\u00e9nitale reste stable tout au long de la vie.<\/p>\n<p>Il est important de faire contr\u00f4ler la vue de son jeune enfant, car si ce trouble de la vision n\u2019est pas d\u00e9cel\u00e9 \u00e0 temps, il peut entra\u00eener des troubles de l\u2019apprentissage de la lecture.<\/p>\n<h2>Les causes et les sympt\u00f4mes<\/h2>\n<p>On dit qu\u2019une personne est astigmate lorsque la vision des lignes horizontales et verticales, de pr\u00e8s comme de loin est floue. Il s\u2019agit d\u2019une l\u00e9g\u00e8re d\u00e9formation de la corn\u00e9e. Autrement dit, l\u2019astigmatisme est li\u00e9 \u00e0 une anomalie de courbure ou du cristallin. Dans ce cas, on observe la confusion de lettres proches comme le H, le M et le N, le E et le B ou le 8 et le 0. A noter que l&rsquo;astigmatisme peut s&rsquo;associer \u00e0 un autre trouble de la vision comme une hyperm\u00e9tropie, une myopie ou encore une presbytie. Les principaux sympt\u00f4mes sont les maux de t\u00eate, les picotements des yeux et vision floue.<\/p>\n<p>En g\u00e9n\u00e9ral, l\u2019astigmatisme est cong\u00e9nital. Toutefois, il peut survenir suite \u00e0 un traumatisme oculaire, une plaie corn\u00e9enne, une infection, une cataracte ou son op\u00e9ration.<\/p>\n<h2>Pr\u00e9vention et traitement<\/h2>\n<p>En fait, on ne peut pas pr\u00e9venir un astigmatisme d\u2019origine cong\u00e9nitale, mais vous pouvez toujours prot\u00e9ger vos yeux en cas d\u2019activit\u00e9s dangereuses. Il est donc vivement conseill\u00e9 de couvrir vos yeux \u00e0 l\u2019aide de lunettes protectrices quand vous faites un bricolage ou du jardinage.<\/p>\n<p>Pour combattre la maladie, la correction repose sur le port de verres (lunettes ou lentilles) ou \u00e0 l\u2019aide d\u2019une chirurgie r\u00e9fractive. A noter que ces traitements sont, en g\u00e9n\u00e9ral, inclus dans les formules de garanties propos\u00e9es par une <strong><a href=\"https:\/\/santors.fr\/prevoyance\/comment-choisir-la-bonne-mutuelle-optique\/\">mutuelle optique<\/a><\/strong>.<\/p>\n<p>Comme il faut tenir compte de toutes les irr\u00e9gularit\u00e9s de la corn\u00e9e, les verres sont parfois d\u00e9licats \u00e0 r\u00e9aliser. De forme torique, ils n&rsquo;ont pas la m\u00eame puissance partout et c&rsquo;est pourquoi il faut \u00e9viter les montures rondes dans lesquelles les verres correcteurs pourraient tourner. Les lentilles de type flexibles ou toriques sont souvent mieux adapt\u00e9es que les lentilles souples sph\u00e9riques.<\/p>\n<p>Gr\u00e2ce \u00e0 la chirurgie r\u00e9fractive, on peut remodeler une corn\u00e9e pour lui redonner une courbure sph\u00e9rique comme une balle de football, sans in\u00e9galit\u00e9s ni bosses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019astigmatisme fait partie des maladies oculaires rencontr\u00e9s chez l\u2019homme. C\u2019est une maladie tr\u00e8s g\u00eanante car elle perturbe \u00e0 la fois la vision de pr\u00e8s et la vision de loin. Ainsi, &hellip; <\/p>\n","protected":false},"author":2,"featured_media":1797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[120],"tags":[295,296],"class_list":["post-1777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assurances","tag-lunettes","tag-vue"],"aioseo_notices":[],"rttpg_featured_image_url":{"full":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",640,427,false],"landscape":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",640,427,false],"portraits":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",640,427,false],"thumbnail":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989-150x150.jpg",150,150,true],"medium":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989-300x200.jpg",300,200,true],"large":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",640,427,false],"1536x1536":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",640,427,false],"2048x2048":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",640,427,false],"hitmag-landscape":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",640,427,false],"hitmag-featured":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",600,400,false],"hitmag-grid":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",322,215,false],"hitmag-list":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",290,193,false],"hitmag-thumbnail":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989.jpg",135,90,false],"400x250-crop":["https:\/\/makedamagazine.com\/blog\/wp-content\/uploads\/2020\/08\/astigmatisme-face-profil-e1616102090989-400x250.jpg",400,250,true]},"rttpg_author":{"display_name":"Claude","author_link":"https:\/\/makedamagazine.com\/blog\/author\/claude\/"},"rttpg_comment":1,"rttpg_category":"<a href=\"https:\/\/makedamagazine.com\/blog\/category\/assurances\/\" rel=\"category tag\">Assurances<\/a>","rttpg_excerpt":"L\u2019astigmatisme fait partie des maladies oculaires rencontr\u00e9s chez l\u2019homme. C\u2019est une maladie tr\u00e8s g\u00eanante car elle perturbe \u00e0 la fois la vision de pr\u00e8s et la vision de loin. Ainsi, &hellip;","_links":{"self":[{"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/posts\/1777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/comments?post=1777"}],"version-history":[{"count":1,"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/posts\/1777\/revisions"}],"predecessor-version":[{"id":2089,"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/posts\/1777\/revisions\/2089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/media\/1797"}],"wp:attachment":[{"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/media?parent=1777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/categories?post=1777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/makedamagazine.com\/blog\/wp-json\/wp\/v2\/tags?post=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}